{"id":14409,"date":"2023-08-08T12:58:22","date_gmt":"2023-08-08T10:58:22","guid":{"rendered":"https:\/\/egn.com\/de\/?post_type=networks&#038;p=14409"},"modified":"2023-11-08T10:42:34","modified_gmt":"2023-11-08T09:42:34","slug":"ceo","status":"publish","type":"networks","link":"https:\/\/egn.com\/de\/peer-groups\/ceo\/","title":{"rendered":"CEO"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14409\" class=\"elementor elementor-14409\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b4d7269 elementor-section-height-min-height hero elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3b4d7269\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/egn.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/08\\\/Ceo-hero-video.m4v&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container elementor-hidden-mobile\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57cc62a5 title__block title__block--center\" data-id=\"57cc62a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-793396d5 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"793396d5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e358457\" data-id=\"e358457\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c5749f7 pre-header elementor-widget elementor-widget-heading\" data-id=\"7c5749f7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">CEO<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2574cbb2 elementor-widget elementor-widget-heading\" data-id=\"2574cbb2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Profitieren Sie vom Wissen der Sparringspartner in der Gruppe \u2013 Denkanst\u00f6\u00dfe und Inspiration f\u00fcr die Unternehmensf\u00fchrung<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27cf3cd3 sub-heading elementor-widget elementor-widget-heading\" data-id=\"27cf3cd3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ihre EGN-Peer Group kann Ihnen etwas bieten, was sie woanders nicht finden werden: Unterst\u00fctzung durch andere F\u00fchrungskr\u00e4fte, die ihre Erfahrungen mit Ihnen teilen.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-244faaae elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"244faaae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b91d2b0 content\" data-id=\"5b91d2b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1e553a7 elementor-section-content-middle timeline timeline--last elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e553a7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f0d7fb8 title__block title__block--left globe-bg globe-bg--darkblue globe-bg-pos--r\" data-id=\"f0d7fb8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b8c3ba pre-header elementor-widget elementor-widget-heading\" data-id=\"3b8c3ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">WERTVOLLE BEZIEHUNGEN<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b10a36f elementor-widget elementor-widget-heading\" data-id=\"b10a36f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Jeder verdient ein gutes Netzwerk<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e87b5cc sub-heading elementor-widget elementor-widget-text-editor\" data-id=\"e87b5cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In all unseren Peer-Groups liegt der Fokus auf vertraulichem Wissensaustausch, Beziehungsaufbau und gegenseitigem Erfahrungsaustausch.<\/p><p>Die neuesten Ideen, Herausforderungen und L\u00f6sungen werden auf den Tisch gebracht und bieten Ihnen optimale Bedingungen, um sowohl pers\u00f6nlich als auch beruflich zu wachsen und zu gedeihen.<\/p><p>Als Mitglied von EGN sparen Sie Zeit und Ressourcen, und Sie haben eine einzigartige M\u00f6glichkeit, Ihren beruflichen Horizont zu erweitern und Ihrem Unternehmen einen Mehrwert zu bieten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-beba3c4 section__img\" data-id=\"beba3c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eda0384 elementor-widget elementor-widget-image\" data-id=\"eda0384\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse4-1024x1024-1.jpg\" class=\"attachment-large size-large wp-image-14418\" alt=\"\" srcset=\"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse4-1024x1024-1.jpg 1024w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse4-1024x1024-1-150x150.jpg 150w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse4-1024x1024-1-768x768.jpg 768w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse4-1024x1024-1-830x830.jpg 830w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse4-1024x1024-1-230x230.jpg 230w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse4-1024x1024-1-350x350.jpg 350w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse4-1024x1024-1-480x480.jpg 480w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse4-1024x1024-1-24x24.jpg 24w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse4-1024x1024-1-36x36.jpg 36w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse4-1024x1024-1-48x48.jpg 48w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-13fb3dde timeline elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13fb3dde\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6de9012 section__img\" data-id=\"6de9012\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26ae2668 elementor-widget elementor-widget-image\" data-id=\"26ae2668\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/content-1-1024x1024-1.jpg\" class=\"attachment-large size-large wp-image-14416\" alt=\"\" srcset=\"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/content-1-1024x1024-1.jpg 1024w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/content-1-1024x1024-1-150x150.jpg 150w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/content-1-1024x1024-1-768x768.jpg 768w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/content-1-1024x1024-1-830x830.jpg 830w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/content-1-1024x1024-1-230x230.jpg 230w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/content-1-1024x1024-1-350x350.jpg 350w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/content-1-1024x1024-1-480x480.jpg 480w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/content-1-1024x1024-1-24x24.jpg 24w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/content-1-1024x1024-1-36x36.jpg 36w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/content-1-1024x1024-1-48x48.jpg 48w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4ff4335b title__block title__block--right globe-bg globe-bg--darkblue globe-bg-pos--l\" data-id=\"4ff4335b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60478f05 pre-header elementor-widget elementor-widget-heading\" data-id=\"60478f05\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">GEMEINSCHAFT VON INDUSTRIEPEERS<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57b20b2f elementor-widget elementor-widget-heading\" data-id=\"57b20b2f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Profil Ihrer Peer Group<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73b424b4 sub-heading elementor-widget elementor-widget-text-editor\" data-id=\"73b424b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CEOs und Strategieleiter von Top-Unternehmen, die in Deutschland t\u00e4tig sind.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7d484f3 elementor-section-content-middle timeline timeline--last elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d484f3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-408ad7bd title__block title__block--left globe-bg globe-bg--darkblue globe-bg-pos--r\" data-id=\"408ad7bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fe9e111 pre-header elementor-widget elementor-widget-heading\" data-id=\"1fe9e111\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">BLEIBEN SIE AUF DEM LAUFENDEN<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-413f84b2 elementor-widget elementor-widget-heading\" data-id=\"413f84b2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agenda<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-467f8261 sub-heading elementor-widget elementor-widget-text-editor\" data-id=\"467f8261\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Als Mitglied bestimmen Sie die Themen der Meetings. Sie stellen vor, was die aktuellen Herausforderungen sind, die Sie zu meistern haben. In der Gruppe entscheiden Sie, welche Themen auf die Tagesordnung kommen und wer dazu einen fachlichen Beitrag leisten kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-58a2197f section__img\" data-id=\"58a2197f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36bb913c elementor-widget elementor-widget-image\" data-id=\"36bb913c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse2-1024x1024-1.jpg\" class=\"attachment-large size-large wp-image-14417\" alt=\"\" srcset=\"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse2-1024x1024-1.jpg 1024w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse2-1024x1024-1-150x150.jpg 150w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse2-1024x1024-1-768x768.jpg 768w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse2-1024x1024-1-830x830.jpg 830w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse2-1024x1024-1-230x230.jpg 230w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse2-1024x1024-1-350x350.jpg 350w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse2-1024x1024-1-480x480.jpg 480w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse2-1024x1024-1-24x24.jpg 24w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse2-1024x1024-1-36x36.jpg 36w, https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/Topledelse2-1024x1024-1-48x48.jpg 48w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87a5a92 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"87a5a92\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ad3cbc\" data-id=\"9ad3cbc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5948af7 elementor-widget elementor-widget-shortcode\" data-id=\"5948af7\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11827\" class=\"elementor elementor-11827\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d111601 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d111601\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d8798c\" data-id=\"5d8798c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-843dfe8 elementor-widget elementor-widget-shortcode\" data-id=\"843dfe8\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"11820\" class=\"elementor elementor-11820\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e0260e2 key-features inverted elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0260e2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b228c9d title__block title__block--center\" data-id=\"b228c9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-236b0ce pre-header elementor-widget elementor-widget-heading\" data-id=\"236b0ce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">MORE THAN A PEER GROUP<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f701fec elementor-widget elementor-widget-heading\" data-id=\"f701fec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die 9 wichtigsten Gr\u00fcnde, beizutreten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d4206ec inverted globe-bg globe-bg-pos--br elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4206ec\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-19b85d1 key-feature-item-wrap\" data-id=\"19b85d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4723691 key-feature--item elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"4723691\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-globe-europe\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWeltweites Peer-Netzwerk\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span class=\"sub-heading\">Wir bieten ein vertrauliches, weltweites Netzwerk aus Peers, die das gemeinsame Ziel haben, voneinander zu lernen und sich weiterzuentwickeln \u2013 und das jeden Tag.<\/span>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fcc982 key-feature--item elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"4fcc982\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-users\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPeer Groups individuell zusammengestellt\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span class=\"sub-heading\">Ihre Peer Group wird von professionellen Network Advisors zusammengestellt, damit sie Ihrer Position fachlich und disziplinarisch entspricht. <\/span>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd9874b key-feature--item elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"fd9874b\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-comments\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMembers\u2019 Universe\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span class=\"sub-heading\">Unser Members' Universe ist eine aus 15.000 Experten bestehende Online-Community. Hier finden Sie die globale Abfragefunktion \"In-App-Messaging\", virtuelle EGN-Gruppen und vieles mehr.<\/span>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adcc987 key-feature--item elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"adcc987\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-shield\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProfessionelle Moderation der Meetings\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span class=\"sub-heading\">Alle Peer Groups werden von unseren erfahrenen und fortlaufend geschulten EGN-Moderatoren begleitet.\n<\/span>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a5d84f key-feature--item elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"9a5d84f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chalkboard-teacher\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCoaching\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span class=\"sub-heading\">Neben dem Erfahrungsaustausch mit Ihren Peers bieten wir Ihnen im Rahmen unseres \"Accelerator\u201c-Programms Eins-zu-Eins-Coaching-Sessions an*.<\/span>\n\n*Momentan noch nicht bundesweit verf\u00fcgbar\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3075371 key-feature--item elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"3075371\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-level-up-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tImmer die passende Peer Group\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span class=\"sub-heading\">W\u00e4hrend Sie sich beruflich weiterentwickeln, \u00e4ndern sich m\u00f6glicherweise Ihre Herausforderungen. Als EGN-Mitglied k\u00f6nnen Sie jederzeit in eine andere Peer Group wechseln, die dann besser zu Ihren aktuellen beruflichen Aufgaben und Anforderungen passt.<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-077f521 key-feature--item elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"077f521\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEvents & Seminare\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span class=\"sub-heading\">Events und Seminare werden in allen L\u00e4ndern f\u00fcr Peer Groups durchgef\u00fchrt, damit sich unsere Mitglieder pers\u00f6nlich und beruflich kontinuierlich weiterentwickeln k\u00f6nnen.<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ddb49c key-feature--item elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"8ddb49c\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pencil-ruler\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAktuelle Beitr\u00e4ge unter Wissenswertes\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span class=\"sub-heading\">Als EGN-Mitglied bekommen Sie einen exklusiven Wissens-Zugang in Form von Management Tools, Fachbeitr\u00e4gen, Best Practices der Mitglieder und vielem mehr.<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a43b5a6 key-feature--item elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"a43b5a6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-business-time\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVorteile f\u00fcr Ihr Unternehmen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span class=\"sub-heading\">Mit einem globalen Pool von +15.000 Experten verschafft EGN Ihrem Unternehmen Zugang zu einer Vielfalt an praxisbew\u00e4hrtem Know-How und zu Einblicken in die aktuellsten Wirtschaftsentwicklungen.<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-feafae5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"feafae5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba9f537\" data-id=\"ba9f537\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbb20d3 elementor-widget elementor-widget-shortcode\" data-id=\"dbb20d3\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"11824\" class=\"elementor elementor-11824\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2dd8ede elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2dd8ede\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ff7e5a4 title__block title__block--center\" data-id=\"ff7e5a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c8b93d pre-header elementor-widget elementor-widget-heading\" data-id=\"3c8b93d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">MEHRWERT F\u00dcR SIE UND IHR UNTERNEHMEN<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9e8c25 elementor-widget elementor-widget-heading\" data-id=\"e9e8c25\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ein starkes Netzwerk von Peers liefert wertvolle Inputs und neue Ideen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-941c048 sub-heading elementor-widget elementor-widget-heading\" data-id=\"941c048\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wir verbinden Sie mit F\u00fchrungskr\u00e4ften, die Ihre Verantwortung und Herausforderungen teilen. Gemeinsam machen wir uns gegenseitig besser.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ba38d6 benefits-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ba38d6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b708729 benefit-block card\" data-id=\"b708729\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5580c3f pre-header elementor-widget elementor-widget-heading\" data-id=\"5580c3f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">UNTERNEHMEN<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc0018b elementor-widget elementor-widget-heading\" data-id=\"bc0018b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vorteile f\u00fcr das Unternehmen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccecb64 elementor-widget elementor-widget-text-editor\" data-id=\"ccecb64\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Mitarbeiterentwicklung \u2013 Verbesserte F\u00e4higkeiten und neue Gesch\u00e4ftseinblicke<\/li><li>Benchmarking und Best Practices<\/li><li>Gro\u00dfe Einsparungen bei Beratern, Produkt- und Marktforschung, Kursen und Schulungen im Allgemeinen.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ac6bedb benefit-block card\" data-id=\"ac6bedb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-692ad21 pre-header elementor-widget elementor-widget-heading\" data-id=\"692ad21\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">MITGLIEDER<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bd1c1f elementor-widget elementor-widget-heading\" data-id=\"3bd1c1f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vorteile f\u00fcr Mitglieder?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1317008 elementor-widget elementor-widget-text-editor\" data-id=\"1317008\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>5 halbt\u00e4gige Peer-Group-Treffen \u00fcber 12 Monate.<\/li><li>Monatliche Webinare, die von fachkundigen Keynote-Speakern zu einer Reihe von F\u00fchrungsthemen geleitet werden.<\/li><li>Member\u2019s Universe: Kontakt oder Anfrage, 24\/7 das ganze Jahr \u00fcber, mit +15.000 Mitgliedern weltweit und rund 800 Fachleuten in Deutschland.<\/li><li>1 pers\u00f6nliches Onboarding-Meeting pro Monat f\u00fcr neu beigetretene EGN-Mitglieder, um Ihr Netzwerk zu erweitern und die Kunst des effektiven Networkings zu erlernen.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47ba6d8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"47ba6d8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64027a9\" data-id=\"64027a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-251ab20 elementor-widget elementor-widget-shortcode\" data-id=\"251ab20\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"11834\" class=\"elementor elementor-11834\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4daf36 trust-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4daf36\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01873e6 title__block title__block--center\" data-id=\"01873e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6864e33 border-emblem elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6864e33\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b12f39b pre-header elementor-widget elementor-widget-heading\" data-id=\"b12f39b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Peace of mind<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45cdd53 elementor-widget elementor-widget-heading\" data-id=\"45cdd53\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sie sind in guten H\u00e4nden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-571f589 trust-items-wrap elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"571f589\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8c46770 item\" data-id=\"8c46770\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e37208 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9e37208\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tools\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d998319 elementor-widget elementor-widget-heading\" data-id=\"d998319\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">30 Jahre Erfahrung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72c6c66 sub-heading elementor-widget elementor-widget-text-editor\" data-id=\"72c6c66\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Was 1992 als Vision eines einzelnen Mannes begann, ist heute ein globales Netzwerk mit 15.000 Mitgliedern in 15 L\u00e4ndern.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2c7c1ea item\" data-id=\"2c7c1ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c1dc0f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0c1dc0f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-fingerprint\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b255a7 elementor-widget elementor-widget-heading\" data-id=\"1b255a7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Die optimale Peer Group<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28bfb07 sub-heading elementor-widget elementor-widget-text-editor\" data-id=\"28bfb07\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unser erfahrenes Vertriebsteam bringt Sie mit anderen F\u00fchrungskr\u00e4ften auf Augenh\u00f6he zusammen \u2013 branchen\u00fcbergreifend und mit \u00e4hnlichen Interessen.<\/p><p>Alle neuen Mitglieder ben\u00f6tigen die Zustimmung der Peer Group Mitglieder \u2013 so ist ausgeschlossen, das u.a. Wettbewerber oder Kunden der Peer Group angeh\u00f6ren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fadaf2a item\" data-id=\"fadaf2a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9d2f48 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c9d2f48\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-shield\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-260db02 elementor-widget elementor-widget-heading\" data-id=\"260db02\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vertrauen und Diskretion<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-583cfd6 sub-heading elementor-widget elementor-widget-text-editor\" data-id=\"583cfd6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fcr ein Netzwerk hat Diskretion die oberste Priorit\u00e4t, daher sind alle unsere Treffen vertraulich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ce7412f cta-block bg-transition pre-footer elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ce7412f\" data-element_type=\"section\" id=\"harvard-cta\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3756f52d wrap\" data-id=\"3756f52d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-25dbad5c elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25dbad5c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-36caff52 title__block\" data-id=\"36caff52\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61368473 elementor-widget elementor-widget-menu-anchor\" data-id=\"61368473\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"anchor-contact-section\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5439eb6b elementor-widget elementor-widget-heading\" data-id=\"5439eb6b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bereit, Ihre Karriere zu ver\u00e4ndern?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65eae2a8 sub-heading elementor-widget elementor-widget-text-editor\" data-id=\"65eae2a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"letter-spacing: 0.4px;\">Lassen Sie einen unserer erfahrenen Berater Sie f\u00fcr ein Gespr\u00e4ch \u00fcber Ihre M\u00f6glichkeiten in unserem Netzwerk anrufen. F\u00fcllen Sie das Formular aus, und wir werden uns bei Ihnen melden.<\/p><p style=\"letter-spacing: 0.4px;\">Wir freuen uns darauf, mit Ihnen dar\u00fcber zu sprechen, wie die Mitgliedschaft einen Unterschied f\u00fcr Sie machen kann.<\/p><p style=\"letter-spacing: 0.4px;\">Finden Sie gleichgesinnte Sparringspartner und sehen Sie, wie Sie einander voranbringen k\u00f6nnen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6aa64b6e\" data-id=\"6aa64b6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea0606b pp-gravity-form-button-custom pp-gravity-form-pagination-buttons-auto elementor-widget elementor-widget-pp-gravity-forms\" data-id=\"ea0606b\" data-element_type=\"widget\" data-widget_type=\"pp-gravity-forms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-contact-form pp-gravity-form\">\n\t\t\t\t\t\t\t\t\t\t<script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework in-page-form_wrapper' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_19' ><form method='post' enctype='multipart\/form-data'  id='gform_19' class='in-page-form' action='\/de\/wp-json\/wp\/v2\/networks\/14409' data-formid='19' novalidate> \r\n <input type='hidden' class='gforms-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/>\n                        <div class='gform-body gform_body'><ul id='gform_fields_19' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_19_6\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_19_6'>Name<\/label><div class='ginput_container'><input name='input_6' id='input_19_6' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_19_6'>Dieses Feld dient zur Validierung und sollte nicht ver\u00e4ndert werden.<\/div><\/li><li id=\"field_19_1\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_19_1'>Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_19_1' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_19_2\" class=\"gfield gfield--type-phone phone-home gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_19_2'>Telefonnummer<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_2' id='input_19_2' type='tel' value='' class='large'   aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_19_3\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_19_3'>E-Mail<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_3' id='input_19_3' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_19_4\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_19_4'>Ihre Funktion im Unternehmen<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_4' id='input_19_4' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_19_5\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_19_5'>Unternehmen<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_5' id='input_19_5' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_19' class='gform_button button gform-button--width-full' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Get in touch'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_19' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_19' id='gform_theme_19' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_19' id='gform_style_settings_19' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_19' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='19' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='DKK' value='8Wh99Fq13PjqNLh03sHU\/GEII14U+YLPVDOvqrAO7a\/S117FU3cAWEtxM7mfow1Z0Kl8A4PRBeTYfXGawEultr169GyvqhnNFAY5+kYcdQGRQ1k=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_19' value='WyJbXSIsIjA1YjMxNzA2MmQ0MTczZjk5NDc1OWIyODJjMTc1ZGVjIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_19' id='gform_target_page_number_19' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_19' id='gform_source_page_number_19' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 19, 'https:\/\/egn.com\/de\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_19').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_19');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_19').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_19').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_19').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_19').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_19').val();gformInitSpinner( 19, 'https:\/\/egn.com\/de\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [19, current_page]);window['gf_submitting_19'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_19').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [19]);window['gf_submitting_19'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_19').text());}else{jQuery('#gform_19').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"19\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_19\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_19\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_19\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 19, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":14411,"template":"elementor_header_footer","categories":[200],"class_list":["post-14409","networks","type-networks","status-publish","has-post-thumbnail","hentry","category-networks"],"acf":[],"yoast_head":"<title>CEO - EGN Deutschland<\/title>\n<meta name=\"description\" content=\"CEO-Peergroups sind vertrauliche Netzwerke, in denen Sparring und Wissensaustausch im Vordergrund stehen. L\u00e4sst sowohl Sie als auch Ihr Unternehmen wachsen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egn.com\/de\/peer-groups\/ceo\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CEO\" \/>\n<meta property=\"og:description\" content=\"CEO Profitieren Sie vom Wissen der Sparringspartner in der Gruppe \u2013 Denkanst\u00f6\u00dfe und Inspiration f\u00fcr die Unternehmensf\u00fchrung Ihre EGN-Peer Group kann Ihnen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egn.com\/de\/peer-groups\/ceo\/\" \/>\n<meta property=\"og:site_name\" content=\"EGN Deutschland\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-08T09:42:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/ceo-video-fallback.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/peer-groups\\\/ceo\\\/\",\"url\":\"https:\\\/\\\/egn.com\\\/de\\\/peer-groups\\\/ceo\\\/\",\"name\":\"CEO - EGN Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/peer-groups\\\/ceo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/peer-groups\\\/ceo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/egn.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/08\\\/ceo-video-fallback.jpg\",\"datePublished\":\"2023-08-08T10:58:22+00:00\",\"dateModified\":\"2023-11-08T09:42:34+00:00\",\"description\":\"CEO-Peergroups sind vertrauliche Netzwerke, in denen Sparring und Wissensaustausch im Vordergrund stehen. L\u00e4sst sowohl Sie als auch Ihr Unternehmen wachsen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/peer-groups\\\/ceo\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/egn.com\\\/de\\\/peer-groups\\\/ceo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/peer-groups\\\/ceo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/egn.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/08\\\/ceo-video-fallback.jpg\",\"contentUrl\":\"https:\\\/\\\/egn.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/08\\\/ceo-video-fallback.jpg\",\"width\":2048,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/peer-groups\\\/ceo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/egn.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Networks\",\"item\":\"https:\\\/\\\/egn.com\\\/de\\\/peer-groups\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CEO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/egn.com\\\/de\\\/\",\"name\":\"EGN Deutschland\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/egn.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/#organization\",\"name\":\"Executives' Global Network | Deutschland\",\"alternateName\":\"EGN Deutschland\",\"url\":\"https:\\\/\\\/egn.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/egn.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2022\\\/10\\\/EGN_SINCE_1992_248.png\",\"contentUrl\":\"https:\\\/\\\/egn.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2022\\\/10\\\/EGN_SINCE_1992_248.png\",\"width\":248,\"height\":96,\"caption\":\"Executives' Global Network | Deutschland\"},\"image\":{\"@id\":\"https:\\\/\\\/egn.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/executives'\u200b-global-network-deutschland\\\/\"]}]}<\/script>","yoast_head_json":{"title":"CEO - EGN Deutschland","description":"CEO-Peergroups sind vertrauliche Netzwerke, in denen Sparring und Wissensaustausch im Vordergrund stehen. L\u00e4sst sowohl Sie als auch Ihr Unternehmen wachsen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egn.com\/de\/peer-groups\/ceo\/","og_locale":"de_DE","og_type":"article","og_title":"CEO","og_description":"CEO Profitieren Sie vom Wissen der Sparringspartner in der Gruppe \u2013 Denkanst\u00f6\u00dfe und Inspiration f\u00fcr die Unternehmensf\u00fchrung Ihre EGN-Peer Group kann Ihnen","og_url":"https:\/\/egn.com\/de\/peer-groups\/ceo\/","og_site_name":"EGN Deutschland","article_modified_time":"2023-11-08T09:42:34+00:00","og_image":[{"width":2048,"height":1080,"url":"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/ceo-video-fallback.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/egn.com\/de\/peer-groups\/ceo\/","url":"https:\/\/egn.com\/de\/peer-groups\/ceo\/","name":"CEO - EGN Deutschland","isPartOf":{"@id":"https:\/\/egn.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/egn.com\/de\/peer-groups\/ceo\/#primaryimage"},"image":{"@id":"https:\/\/egn.com\/de\/peer-groups\/ceo\/#primaryimage"},"thumbnailUrl":"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/ceo-video-fallback.jpg","datePublished":"2023-08-08T10:58:22+00:00","dateModified":"2023-11-08T09:42:34+00:00","description":"CEO-Peergroups sind vertrauliche Netzwerke, in denen Sparring und Wissensaustausch im Vordergrund stehen. L\u00e4sst sowohl Sie als auch Ihr Unternehmen wachsen.","breadcrumb":{"@id":"https:\/\/egn.com\/de\/peer-groups\/ceo\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/egn.com\/de\/peer-groups\/ceo\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/egn.com\/de\/peer-groups\/ceo\/#primaryimage","url":"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/ceo-video-fallback.jpg","contentUrl":"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2023\/08\/ceo-video-fallback.jpg","width":2048,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/egn.com\/de\/peer-groups\/ceo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/egn.com\/de\/"},{"@type":"ListItem","position":2,"name":"Networks","item":"https:\/\/egn.com\/de\/peer-groups\/"},{"@type":"ListItem","position":3,"name":"CEO"}]},{"@type":"WebSite","@id":"https:\/\/egn.com\/de\/#website","url":"https:\/\/egn.com\/de\/","name":"EGN Deutschland","description":"","publisher":{"@id":"https:\/\/egn.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egn.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/egn.com\/de\/#organization","name":"Executives' Global Network | Deutschland","alternateName":"EGN Deutschland","url":"https:\/\/egn.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/egn.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2022\/10\/EGN_SINCE_1992_248.png","contentUrl":"https:\/\/egn.com\/de\/wp-content\/uploads\/sites\/15\/2022\/10\/EGN_SINCE_1992_248.png","width":248,"height":96,"caption":"Executives' Global Network | Deutschland"},"image":{"@id":"https:\/\/egn.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/executives'\u200b-global-network-deutschland\/"]}]}},"_links":{"self":[{"href":"https:\/\/egn.com\/de\/wp-json\/wp\/v2\/networks\/14409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egn.com\/de\/wp-json\/wp\/v2\/networks"}],"about":[{"href":"https:\/\/egn.com\/de\/wp-json\/wp\/v2\/types\/networks"}],"version-history":[{"count":15,"href":"https:\/\/egn.com\/de\/wp-json\/wp\/v2\/networks\/14409\/revisions"}],"predecessor-version":[{"id":14570,"href":"https:\/\/egn.com\/de\/wp-json\/wp\/v2\/networks\/14409\/revisions\/14570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/egn.com\/de\/wp-json\/wp\/v2\/media\/14411"}],"wp:attachment":[{"href":"https:\/\/egn.com\/de\/wp-json\/wp\/v2\/media?parent=14409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/egn.com\/de\/wp-json\/wp\/v2\/categories?post=14409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}